{"id":29847,"date":"2024-06-06T11:49:35","date_gmt":"2024-06-06T09:49:35","guid":{"rendered":"https:\/\/www.compagniadisanpaolo.it\/?post_type=documenti&#038;p=29847"},"modified":"2024-06-06T11:49:35","modified_gmt":"2024-06-06T09:49:35","slug":"linee-guida-per-la-richiesta-di-contributo-entro-la-call-nidi-e-scuole-dellinfanzia","status":"publish","type":"documenti","link":"https:\/\/stage.compagniadisanpaolo.gag.it\/it\/documenti\/linee-guida-per-la-richiesta-di-contributo-entro-la-call-nidi-e-scuole-dellinfanzia\/","title":{"rendered":"Linee Guida per la richiesta di contributo entro la Call \u201cNidi e Scuole dell\u2019Infanzia\u201d"},"content":{"rendered":"","protected":false},"menu_order":0,"template":"","meta":{"_acf_changed":false,"content-type":""},"tags":[],"class_list":["post-29847","documenti","type-documenti","status-publish","hentry","entry","post-inner"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Linee Guida per la richiesta di contributo entro la Call \u201cNidi e Scuole dell\u2019Infanzia\u201d - Fondazione Compagnia di San Paolo<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Linee Guida per la richiesta di contributo entro la Call \u201cNidi e Scuole dell\u2019Infanzia\u201d - Fondazione Compagnia di San Paolo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/stage.compagniadisanpaolo.gag.it\/it\/documenti\/linee-guida-per-la-richiesta-di-contributo-entro-la-call-nidi-e-scuole-dellinfanzia\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondazione Compagnia di San Paolo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CompagniaDiSanPaolo\" \/>\n<meta property=\"og:image\" content=\"https:\/\/stage.compagniadisanpaolo.gag.it\/wp-content\/uploads\/alternate-social.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CSP_live\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/stage.compagniadisanpaolo.gag.it\\\/it\\\/documenti\\\/linee-guida-per-la-richiesta-di-contributo-entro-la-call-nidi-e-scuole-dellinfanzia\\\/\",\"url\":\"https:\\\/\\\/stage.compagniadisanpaolo.gag.it\\\/it\\\/documenti\\\/linee-guida-per-la-richiesta-di-contributo-entro-la-call-nidi-e-scuole-dellinfanzia\\\/\",\"name\":\"Linee Guida per la richiesta di contributo entro la Call \u201cNidi e Scuole dell\u2019Infanzia\u201d - Fondazione Compagnia di San Paolo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/stage.compagniadisanpaolo.gag.it\\\/it\\\/#website\"},\"datePublished\":\"2024-06-06T09:49:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/stage.compagniadisanpaolo.gag.it\\\/it\\\/documenti\\\/linee-guida-per-la-richiesta-di-contributo-entro-la-call-nidi-e-scuole-dellinfanzia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/stage.compagniadisanpaolo.gag.it\\\/it\\\/documenti\\\/linee-guida-per-la-richiesta-di-contributo-entro-la-call-nidi-e-scuole-dellinfanzia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/stage.compagniadisanpaolo.gag.it\\\/it\\\/documenti\\\/linee-guida-per-la-richiesta-di-contributo-entro-la-call-nidi-e-scuole-dellinfanzia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/stage.compagniadisanpaolo.gag.it\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Linee Guida per la richiesta di contributo entro la Call \u201cNidi e Scuole dell\u2019Infanzia\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/stage.compagniadisanpaolo.gag.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/stage.compagniadisanpaolo.gag.it\\\/it\\\/\",\"name\":\"Fondazione Compagnia di San Paolo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/stage.compagniadisanpaolo.gag.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/stage.compagniadisanpaolo.gag.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/stage.compagniadisanpaolo.gag.it\\\/it\\\/#organization\",\"name\":\"Fondazione Compagnia di San Paolo\",\"url\":\"https:\\\/\\\/stage.compagniadisanpaolo.gag.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/stage.compagniadisanpaolo.gag.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/stage.compagniadisanpaolo.gag.it\\\/wp-content\\\/uploads\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/stage.compagniadisanpaolo.gag.it\\\/wp-content\\\/uploads\\\/logo.svg\",\"width\":769,\"height\":323,\"caption\":\"Fondazione Compagnia di San Paolo\"},\"image\":{\"@id\":\"https:\\\/\\\/stage.compagniadisanpaolo.gag.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CompagniaDiSanPaolo\",\"https:\\\/\\\/x.com\\\/CSP_live\",\"http:\\\/\\\/instagram.com\\\/compagniadisanpaolo?ref=badge\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/compagnia-di-san-paolo\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/compagniadisanpaolo\",\"https:\\\/\\\/it.wikipedia.org\\\/wiki\\\/Compagnia_di_San_Paolo\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Linee Guida per la richiesta di contributo entro la Call \u201cNidi e Scuole dell\u2019Infanzia\u201d - Fondazione Compagnia di San Paolo","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"Linee Guida per la richiesta di contributo entro la Call \u201cNidi e Scuole dell\u2019Infanzia\u201d - Fondazione Compagnia di San Paolo","og_url":"https:\/\/stage.compagniadisanpaolo.gag.it\/it\/documenti\/linee-guida-per-la-richiesta-di-contributo-entro-la-call-nidi-e-scuole-dellinfanzia\/","og_site_name":"Fondazione Compagnia di San Paolo","article_publisher":"https:\/\/www.facebook.com\/CompagniaDiSanPaolo","og_image":[{"width":1200,"height":900,"url":"https:\/\/stage.compagniadisanpaolo.gag.it\/wp-content\/uploads\/alternate-social.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@CSP_live","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/stage.compagniadisanpaolo.gag.it\/it\/documenti\/linee-guida-per-la-richiesta-di-contributo-entro-la-call-nidi-e-scuole-dellinfanzia\/","url":"https:\/\/stage.compagniadisanpaolo.gag.it\/it\/documenti\/linee-guida-per-la-richiesta-di-contributo-entro-la-call-nidi-e-scuole-dellinfanzia\/","name":"Linee Guida per la richiesta di contributo entro la Call \u201cNidi e Scuole dell\u2019Infanzia\u201d - Fondazione Compagnia di San Paolo","isPartOf":{"@id":"https:\/\/stage.compagniadisanpaolo.gag.it\/it\/#website"},"datePublished":"2024-06-06T09:49:35+00:00","breadcrumb":{"@id":"https:\/\/stage.compagniadisanpaolo.gag.it\/it\/documenti\/linee-guida-per-la-richiesta-di-contributo-entro-la-call-nidi-e-scuole-dellinfanzia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/stage.compagniadisanpaolo.gag.it\/it\/documenti\/linee-guida-per-la-richiesta-di-contributo-entro-la-call-nidi-e-scuole-dellinfanzia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/stage.compagniadisanpaolo.gag.it\/it\/documenti\/linee-guida-per-la-richiesta-di-contributo-entro-la-call-nidi-e-scuole-dellinfanzia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/stage.compagniadisanpaolo.gag.it\/it\/"},{"@type":"ListItem","position":2,"name":"Linee Guida per la richiesta di contributo entro la Call \u201cNidi e Scuole dell\u2019Infanzia\u201d"}]},{"@type":"WebSite","@id":"https:\/\/stage.compagniadisanpaolo.gag.it\/it\/#website","url":"https:\/\/stage.compagniadisanpaolo.gag.it\/it\/","name":"Fondazione Compagnia di San Paolo","description":"","publisher":{"@id":"https:\/\/stage.compagniadisanpaolo.gag.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/stage.compagniadisanpaolo.gag.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/stage.compagniadisanpaolo.gag.it\/it\/#organization","name":"Fondazione Compagnia di San Paolo","url":"https:\/\/stage.compagniadisanpaolo.gag.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/stage.compagniadisanpaolo.gag.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/stage.compagniadisanpaolo.gag.it\/wp-content\/uploads\/logo.svg","contentUrl":"https:\/\/stage.compagniadisanpaolo.gag.it\/wp-content\/uploads\/logo.svg","width":769,"height":323,"caption":"Fondazione Compagnia di San Paolo"},"image":{"@id":"https:\/\/stage.compagniadisanpaolo.gag.it\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CompagniaDiSanPaolo","https:\/\/x.com\/CSP_live","http:\/\/instagram.com\/compagniadisanpaolo?ref=badge","https:\/\/www.linkedin.com\/company\/compagnia-di-san-paolo","https:\/\/www.youtube.com\/user\/compagniadisanpaolo","https:\/\/it.wikipedia.org\/wiki\/Compagnia_di_San_Paolo"]}]}},"_links":{"self":[{"href":"https:\/\/stage.compagniadisanpaolo.gag.it\/it\/wp-json\/wp\/v2\/documenti\/29847","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stage.compagniadisanpaolo.gag.it\/it\/wp-json\/wp\/v2\/documenti"}],"about":[{"href":"https:\/\/stage.compagniadisanpaolo.gag.it\/it\/wp-json\/wp\/v2\/types\/documenti"}],"wp:attachment":[{"href":"https:\/\/stage.compagniadisanpaolo.gag.it\/it\/wp-json\/wp\/v2\/media?parent=29847"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/stage.compagniadisanpaolo.gag.it\/it\/wp-json\/wp\/v2\/tags?post=29847"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}